{"id":9043,"date":"2020-09-08T09:36:56","date_gmt":"2020-09-08T07:36:56","guid":{"rendered":"http:\/\/europa.basilicata.it\/feasr\/?p=9043"},"modified":"2021-02-23T18:53:16","modified_gmt":"2021-02-23T17:53:16","slug":"call-farm2fork-selezione-prodotti-e-servizi-nel-settore-agroalimentare","status":"publish","type":"post","link":"https:\/\/europa.regione.basilicata.it\/feasr\/call-farm2fork-selezione-prodotti-e-servizi-nel-settore-agroalimentare\/","title":{"rendered":"Farm2Fork, Selezione prodotti e servizi nel settore agroalimentare\u00a0"},"content":{"rendered":"<p>[:it]Si segnala che \u00e8 aperta una call per la ricerca di prodotti e servizi innovativi per:<\/p>\n<p>* Minimizzazione degli effetti negativi della pandemia COVID nel settore agroalimentare<br \/>\n* Aumentare la resilienza della produzione alimentare e dei sistemi di approvvigionamento alimentare in situazioni di pandemia<\/p>\n<p style=\"text-align: justify;\">L&#8217;obiettivo \u00e8 selezionare prodotti e servizi utilizzabili nel settore agroalimentare, che stanno rispondendo agli effetti della crisi COVID-19. Prodotti e\u00a0 servizi possono essere candidati come Minimum Viable Products (MVP) o come Prodotti e servizi che possono essere utilizzati, promuovibili e commerciabili.<\/p>\n<p>La call ha <span style=\"color: #ff0000;\"><strong>SCADENZA 7 OTTOBRE 2020, ORE 17:00<\/strong><\/span><\/p>\n<p>Maggiori informazioni sono disponibili sul portale <a href=\"https:\/\/itc-cluster.com\/farm2forkhack\/\"><strong>FARM2FORK HACK<\/strong><\/a><\/p>\n<p>&nbsp;[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:it]Si segnala che \u00e8 aperta una call per la ricerca di prodotti e servizi innovativi per: * Minimizzazione degli effetti<\/p>\n","protected":false},"author":6,"featured_media":10281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15,16],"tags":[],"class_list":["post-9043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-news"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:30:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/posts\/9043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/comments?post=9043"}],"version-history":[{"count":4,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/posts\/9043\/revisions"}],"predecessor-version":[{"id":10285,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/posts\/9043\/revisions\/10285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/media\/10281"}],"wp:attachment":[{"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/media?parent=9043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/categories?post=9043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europa.regione.basilicata.it\/feasr\/wp-json\/wp\/v2\/tags?post=9043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}